{"id":139,"count":4,"description":"","link":"https:\/\/elteuperfum.com\/ca\/categoria-producto\/perfumes\/equivalencia-burberry\/","name":"Equivalencia Burberry","slug":"equivalencia-burberry","taxonomy":"product_cat","parent":101,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Equivalencia Burberry archivos - El teu perfum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equivalencia Burberry archivos - El teu perfum\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/\" \/>\n<meta property=\"og:site_name\" content=\"El teu perfum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/\",\"url\":\"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/\",\"name\":\"Equivalencia Burberry archivos - El teu perfum\",\"isPartOf\":{\"@id\":\"https:\/\/elteuperfum.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/elteuperfum.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perfumes\",\"item\":\"https:\/\/elteuperfum.com\/ca\/categoria-producto\/perfumes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Equivalencia Burberry\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elteuperfum.com\/#website\",\"url\":\"https:\/\/elteuperfum.com\/\",\"name\":\"El teu perfum\",\"description\":\"La teva ess\u00e8ncia, al millor preu.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elteuperfum.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equivalencia Burberry archivos - El teu perfum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/","og_locale":"ca_ES","og_type":"article","og_title":"Equivalencia Burberry archivos - El teu perfum","og_url":"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/","og_site_name":"El teu perfum","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/","url":"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/","name":"Equivalencia Burberry archivos - El teu perfum","isPartOf":{"@id":"https:\/\/elteuperfum.com\/#website"},"breadcrumb":{"@id":"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/elteuperfum.com\/categoria-producto\/perfumes\/equivalencia-burberry\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elteuperfum.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Perfumes","item":"https:\/\/elteuperfum.com\/ca\/categoria-producto\/perfumes\/"},{"@type":"ListItem","position":3,"name":"Equivalencia Burberry"}]},{"@type":"WebSite","@id":"https:\/\/elteuperfum.com\/#website","url":"https:\/\/elteuperfum.com\/","name":"El teu perfum","description":"La teva ess\u00e8ncia, al millor preu.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elteuperfum.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_cat\/139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_cat\/101"}],"wp:post_type":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product?product_cat=139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}