{"id":21508,"date":"2025-11-17T10:13:15","date_gmt":"2025-11-17T10:13:15","guid":{"rendered":"https:\/\/elteuperfum.com\/?post_type=product&#038;p=21508"},"modified":"2026-03-04T08:55:07","modified_gmt":"2026-03-04T07:55:07","slug":"230-equivalencia-one-million-lucky","status":"publish","type":"product","link":"https:\/\/elteuperfum.com\/ca\/producto\/230-equivalencia-one-million-lucky\/","title":{"rendered":"#230- Equivalencia ONE MILLION LUCKY"},"content":{"rendered":"<div id=\"pageContainer25\" class=\"_page_x434h_98\" role=\"presentation\" data-index=\"24\" aria-label=\"P\u00e1gina 25\">\n<p>familia olfativa Amaderada para Hombres.<br \/>\nLas Notas de Salida son ciruela, notas oz\u00f3nicas, toronja (pomelo) y bergamota;<br \/>\nlas Notas de Coraz\u00f3n son avellana, miel, cedro, madera de cachemira, flor de azahar del naranjo y jazm\u00edn;<br \/>\nlas Notas de Fondo son Amberwood, pachul\u00ed, musgo de roble y vetiver.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>familia olfativa Amaderada para Hombres. Las Notas de Salida son ciruela, notas oz\u00f3nicas, toronja (pomelo) y bergamota; las Notas de<\/p>\n","protected":false},"featured_media":21988,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[131,103,101],"product_tag":[],"class_list":{"0":"post-21508","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-equivalencia-paco-rabanne","7":"product_cat-para-hombre","8":"product_cat-perfumes","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>#230- Equivalencia ONE MILLION LUCKY - El teu perfum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#230- Equivalencia ONE MILLION LUCKY - El teu perfum\" \/>\n<meta property=\"og:description\" content=\"familia olfativa Amaderada para Hombres. Las Notas de Salida son ciruela, notas oz\u00f3nicas, toronja (pomelo) y bergamota; las Notas de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/\" \/>\n<meta property=\"og:site_name\" content=\"El teu perfum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-04T07:55:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-MASC.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/\",\"url\":\"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/\",\"name\":\"#230- Equivalencia ONE MILLION LUCKY - El teu perfum\",\"isPartOf\":{\"@id\":\"https:\/\/elteuperfum.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-MASC.jpg\",\"datePublished\":\"2025-11-17T10:13:15+00:00\",\"dateModified\":\"2026-03-04T07:55:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/#primaryimage\",\"url\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-MASC.jpg\",\"contentUrl\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-MASC.jpg\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/elteuperfum.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\/\/elteuperfum.com\/tienda-de-perfumes-online\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"#230- Equivalencia ONE MILLION LUCKY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elteuperfum.com\/#website\",\"url\":\"https:\/\/elteuperfum.com\/\",\"name\":\"El teu perfum\",\"description\":\"La teva ess\u00e8ncia, al millor preu.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elteuperfum.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#230- Equivalencia ONE MILLION LUCKY - El teu perfum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/","og_locale":"ca_ES","og_type":"article","og_title":"#230- Equivalencia ONE MILLION LUCKY - El teu perfum","og_description":"familia olfativa Amaderada para Hombres. Las Notas de Salida son ciruela, notas oz\u00f3nicas, toronja (pomelo) y bergamota; las Notas de","og_url":"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/","og_site_name":"El teu perfum","article_modified_time":"2026-03-04T07:55:07+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-MASC.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/","url":"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/","name":"#230- Equivalencia ONE MILLION LUCKY - El teu perfum","isPartOf":{"@id":"https:\/\/elteuperfum.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/#primaryimage"},"image":{"@id":"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/#primaryimage"},"thumbnailUrl":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-MASC.jpg","datePublished":"2025-11-17T10:13:15+00:00","dateModified":"2026-03-04T07:55:07+00:00","breadcrumb":{"@id":"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/#primaryimage","url":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-MASC.jpg","contentUrl":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-MASC.jpg","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/elteuperfum.com\/producto\/230-equivalencia-one-million-lucky\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elteuperfum.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Botiga","item":"https:\/\/elteuperfum.com\/tienda-de-perfumes-online\/"},{"@type":"ListItem","position":3,"name":"#230- Equivalencia ONE MILLION LUCKY"}]},{"@type":"WebSite","@id":"https:\/\/elteuperfum.com\/#website","url":"https:\/\/elteuperfum.com\/","name":"El teu perfum","description":"La teva ess\u00e8ncia, al millor preu.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elteuperfum.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product\/21508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/comments?post=21508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/media\/21988"}],"wp:attachment":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/media?parent=21508"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_brand?post=21508"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_cat?post=21508"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_tag?post=21508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}