{"id":21216,"date":"2025-11-14T10:51:56","date_gmt":"2025-11-14T10:51:56","guid":{"rendered":"https:\/\/elteuperfum.com\/?post_type=product&#038;p=21216"},"modified":"2026-03-05T11:35:17","modified_gmt":"2026-03-05T10:35:17","slug":"573-equivalencia-zadig-eau-de-parfum","status":"publish","type":"product","link":"https:\/\/elteuperfum.com\/ca\/producto\/573-equivalencia-zadig-eau-de-parfum\/","title":{"rendered":"#573- Equivalencia Zadig Eau de Parfum"},"content":{"rendered":"<div id=\"pageContainer25\" class=\"_page_x434h_98\" role=\"presentation\" data-index=\"24\" aria-label=\"P\u00e1gina 25\">\n<p>Las Notas de Salida son s\u00e9samo (ajonjol\u00ed), jengibre, pimienta blanca y pimienta<br \/>\nnegra;<br \/>\nlas Notas de Coraz\u00f3n son flor de azahar del naranjo y esencia de neroli;<br \/>\nlas Notas de Fondo son Chantilly Cream, vainilla y s\u00e1ndalo.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las Notas de Salida son s\u00e9samo (ajonjol\u00ed), jengibre, pimienta blanca y pimienta negra; las Notas de Coraz\u00f3n son flor de<\/p>\n","protected":false},"featured_media":21984,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[154,104,101],"product_tag":[],"class_list":{"0":"post-21216","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-equivalencia-zadig-voltaire","7":"product_cat-para-mujer","8":"product_cat-perfumes","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>#573- Equivalencia Zadig Eau de Parfum - El teu perfum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#573- Equivalencia Zadig Eau de Parfum - El teu perfum\" \/>\n<meta property=\"og:description\" content=\"Las Notas de Salida son s\u00e9samo (ajonjol\u00ed), jengibre, pimienta blanca y pimienta negra; las Notas de Coraz\u00f3n son flor de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/\" \/>\n<meta property=\"og:site_name\" content=\"El teu perfum\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T10:35:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/\",\"url\":\"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/\",\"name\":\"#573- Equivalencia Zadig Eau de Parfum - El teu perfum\",\"isPartOf\":{\"@id\":\"https:\/\/elteuperfum.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"datePublished\":\"2025-11-14T10:51:56+00:00\",\"dateModified\":\"2026-03-05T10:35:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/#primaryimage\",\"url\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"contentUrl\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"width\":2000,\"height\":2000,\"caption\":\"Comprar perfumes de equivalencia en El Teu Perfum, en Balaguer.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/elteuperfum.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\/\/elteuperfum.com\/tienda-de-perfumes-online\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"#573- Equivalencia Zadig Eau de Parfum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elteuperfum.com\/#website\",\"url\":\"https:\/\/elteuperfum.com\/\",\"name\":\"El teu perfum\",\"description\":\"La teva ess\u00e8ncia, al millor preu.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elteuperfum.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#573- Equivalencia Zadig Eau de Parfum - El teu perfum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/","og_locale":"ca_ES","og_type":"article","og_title":"#573- Equivalencia Zadig Eau de Parfum - El teu perfum","og_description":"Las Notas de Salida son s\u00e9samo (ajonjol\u00ed), jengibre, pimienta blanca y pimienta negra; las Notas de Coraz\u00f3n son flor de","og_url":"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/","og_site_name":"El teu perfum","article_modified_time":"2026-03-05T10:35:17+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/","url":"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/","name":"#573- Equivalencia Zadig Eau de Parfum - El teu perfum","isPartOf":{"@id":"https:\/\/elteuperfum.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/#primaryimage"},"image":{"@id":"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/#primaryimage"},"thumbnailUrl":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","datePublished":"2025-11-14T10:51:56+00:00","dateModified":"2026-03-05T10:35:17+00:00","breadcrumb":{"@id":"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/#primaryimage","url":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","contentUrl":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","width":2000,"height":2000,"caption":"Comprar perfumes de equivalencia en El Teu Perfum, en Balaguer."},{"@type":"BreadcrumbList","@id":"https:\/\/elteuperfum.com\/producto\/573-equivalencia-zadig-eau-de-parfum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elteuperfum.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Botiga","item":"https:\/\/elteuperfum.com\/tienda-de-perfumes-online\/"},{"@type":"ListItem","position":3,"name":"#573- Equivalencia Zadig Eau de Parfum"}]},{"@type":"WebSite","@id":"https:\/\/elteuperfum.com\/#website","url":"https:\/\/elteuperfum.com\/","name":"El teu perfum","description":"La teva ess\u00e8ncia, al millor preu.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elteuperfum.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product\/21216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/comments?post=21216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/media\/21984"}],"wp:attachment":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/media?parent=21216"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_brand?post=21216"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_cat?post=21216"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_tag?post=21216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}