{"id":20988,"date":"2025-11-14T08:24:19","date_gmt":"2025-11-14T08:24:19","guid":{"rendered":"https:\/\/elteuperfum.com\/?post_type=product&#038;p=20988"},"modified":"2025-12-10T09:30:29","modified_gmt":"2025-12-10T08:30:29","slug":"523-equivalencia-idole-lancome","status":"publish","type":"product","link":"https:\/\/elteuperfum.com\/ca\/producto\/523-equivalencia-idole-lancome\/","title":{"rendered":"#523- Equivalencia ID\u00d4LE, LANC\u00d4ME"},"content":{"rendered":"<p>Familia Olfativa: Chipre Floral Notas de Salida: Bergamota y pera. Notas Coraz\u00f3n: Rosa turca, rosa de Mai y jazm\u00edn de la india. Notas de fondo: Almizcle blanco y vainilla.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Familia Olfativa: Chipre Floral Notas de Salida: Bergamota y pera. Notas Coraz\u00f3n: Rosa turca, rosa de Mai y jazm\u00edn de<\/p>\n","protected":false},"featured_media":21984,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[136,104,101],"product_tag":[],"class_list":{"0":"post-20988","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-equivalencia-lancome-perfumes","7":"product_cat-para-mujer","8":"product_cat-perfumes","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>#523- Equivalencia ID\u00d4LE, LANC\u00d4ME - El teu perfum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#523- Equivalencia ID\u00d4LE, LANC\u00d4ME - El teu perfum\" \/>\n<meta property=\"og:description\" content=\"Familia Olfativa: Chipre Floral Notas de Salida: Bergamota y pera. Notas Coraz\u00f3n: Rosa turca, rosa de Mai y jazm\u00edn de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/\" \/>\n<meta property=\"og:site_name\" content=\"El teu perfum\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-10T08:30:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/\",\"url\":\"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/\",\"name\":\"#523- Equivalencia ID\u00d4LE, LANC\u00d4ME - El teu perfum\",\"isPartOf\":{\"@id\":\"https:\/\/elteuperfum.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"datePublished\":\"2025-11-14T08:24:19+00:00\",\"dateModified\":\"2025-12-10T08:30:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/#primaryimage\",\"url\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"contentUrl\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"width\":2000,\"height\":2000,\"caption\":\"Comprar perfumes de equivalencia en El Teu Perfum, en Balaguer.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/elteuperfum.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\/\/elteuperfum.com\/tienda-de-perfumes-online\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"#523- Equivalencia ID\u00d4LE, LANC\u00d4ME\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elteuperfum.com\/#website\",\"url\":\"https:\/\/elteuperfum.com\/\",\"name\":\"El teu perfum\",\"description\":\"La teva ess\u00e8ncia, al millor preu.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elteuperfum.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#523- Equivalencia ID\u00d4LE, LANC\u00d4ME - El teu perfum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/","og_locale":"ca_ES","og_type":"article","og_title":"#523- Equivalencia ID\u00d4LE, LANC\u00d4ME - El teu perfum","og_description":"Familia Olfativa: Chipre Floral Notas de Salida: Bergamota y pera. Notas Coraz\u00f3n: Rosa turca, rosa de Mai y jazm\u00edn de","og_url":"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/","og_site_name":"El teu perfum","article_modified_time":"2025-12-10T08:30:29+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/","url":"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/","name":"#523- Equivalencia ID\u00d4LE, LANC\u00d4ME - El teu perfum","isPartOf":{"@id":"https:\/\/elteuperfum.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/#primaryimage"},"image":{"@id":"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/#primaryimage"},"thumbnailUrl":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","datePublished":"2025-11-14T08:24:19+00:00","dateModified":"2025-12-10T08:30:29+00:00","breadcrumb":{"@id":"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/#primaryimage","url":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","contentUrl":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","width":2000,"height":2000,"caption":"Comprar perfumes de equivalencia en El Teu Perfum, en Balaguer."},{"@type":"BreadcrumbList","@id":"https:\/\/elteuperfum.com\/producto\/523-equivalencia-idole-lancome\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elteuperfum.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Botiga","item":"https:\/\/elteuperfum.com\/tienda-de-perfumes-online\/"},{"@type":"ListItem","position":3,"name":"#523- Equivalencia ID\u00d4LE, LANC\u00d4ME"}]},{"@type":"WebSite","@id":"https:\/\/elteuperfum.com\/#website","url":"https:\/\/elteuperfum.com\/","name":"El teu perfum","description":"La teva ess\u00e8ncia, al millor preu.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elteuperfum.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product\/20988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/comments?post=20988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/media\/21984"}],"wp:attachment":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/media?parent=20988"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_brand?post=20988"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_cat?post=20988"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_tag?post=20988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}