{"id":20622,"date":"2025-11-13T09:16:20","date_gmt":"2025-11-13T09:16:20","guid":{"rendered":"https:\/\/elteuperfum.com\/?post_type=product&#038;p=20622"},"modified":"2025-12-05T13:27:35","modified_gmt":"2025-12-05T13:27:35","slug":"24-equivalencia-ralph-de-ralph-lauren","status":"publish","type":"product","link":"https:\/\/elteuperfum.com\/ca\/producto\/24-equivalencia-ralph-de-ralph-lauren\/","title":{"rendered":"#24- Equivalencia Ralph de Ralph Lauren"},"content":{"rendered":"<p>Es una fragancia de la familia olfativa Floral Frutal para Mujeres. Las Notas de Salida son osmanto japon\u00e9s (olivo oloroso japon\u00e9s), hojas del manzano y mandarina italiana. Las Notas de Coraz\u00f3n son magnolia, boronia parda y fresia amarilla. Las Notas de Fondo son almizcle e iris blanco.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es una fragancia de la familia olfativa Floral Frutal para Mujeres. Las Notas de Salida son osmanto japon\u00e9s (olivo oloroso<\/p>\n","protected":false},"featured_media":21984,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[132,104,101],"product_tag":[],"class_list":{"0":"post-20622","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-equivalencia-ralph-lauren","7":"product_cat-para-mujer","8":"product_cat-perfumes","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>#24- Equivalencia Ralph de Ralph Lauren - El teu perfum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#24- Equivalencia Ralph de Ralph Lauren - El teu perfum\" \/>\n<meta property=\"og:description\" content=\"Es una fragancia de la familia olfativa Floral Frutal para Mujeres. Las Notas de Salida son osmanto japon\u00e9s (olivo oloroso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/\" \/>\n<meta property=\"og:site_name\" content=\"El teu perfum\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-05T13:27:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/\",\"url\":\"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/\",\"name\":\"#24- Equivalencia Ralph de Ralph Lauren - El teu perfum\",\"isPartOf\":{\"@id\":\"https:\/\/elteuperfum.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"datePublished\":\"2025-11-13T09:16:20+00:00\",\"dateModified\":\"2025-12-05T13:27:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/#primaryimage\",\"url\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"contentUrl\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"width\":2000,\"height\":2000,\"caption\":\"Comprar perfumes de equivalencia en El Teu Perfum, en Balaguer.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/elteuperfum.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\/\/elteuperfum.com\/tienda-de-perfumes-online\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"#24- Equivalencia Ralph de Ralph Lauren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elteuperfum.com\/#website\",\"url\":\"https:\/\/elteuperfum.com\/\",\"name\":\"El teu perfum\",\"description\":\"La teva ess\u00e8ncia, al millor preu.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elteuperfum.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#24- Equivalencia Ralph de Ralph Lauren - El teu perfum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/","og_locale":"ca_ES","og_type":"article","og_title":"#24- Equivalencia Ralph de Ralph Lauren - El teu perfum","og_description":"Es una fragancia de la familia olfativa Floral Frutal para Mujeres. Las Notas de Salida son osmanto japon\u00e9s (olivo oloroso","og_url":"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/","og_site_name":"El teu perfum","article_modified_time":"2025-12-05T13:27:35+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/","url":"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/","name":"#24- Equivalencia Ralph de Ralph Lauren - El teu perfum","isPartOf":{"@id":"https:\/\/elteuperfum.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/#primaryimage"},"image":{"@id":"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/#primaryimage"},"thumbnailUrl":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","datePublished":"2025-11-13T09:16:20+00:00","dateModified":"2025-12-05T13:27:35+00:00","breadcrumb":{"@id":"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/#primaryimage","url":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","contentUrl":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","width":2000,"height":2000,"caption":"Comprar perfumes de equivalencia en El Teu Perfum, en Balaguer."},{"@type":"BreadcrumbList","@id":"https:\/\/elteuperfum.com\/producto\/24-equivalencia-ralph-de-ralph-lauren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elteuperfum.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Botiga","item":"https:\/\/elteuperfum.com\/tienda-de-perfumes-online\/"},{"@type":"ListItem","position":3,"name":"#24- Equivalencia Ralph de Ralph Lauren"}]},{"@type":"WebSite","@id":"https:\/\/elteuperfum.com\/#website","url":"https:\/\/elteuperfum.com\/","name":"El teu perfum","description":"La teva ess\u00e8ncia, al millor preu.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elteuperfum.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product\/20622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/comments?post=20622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/media\/21984"}],"wp:attachment":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/media?parent=20622"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_brand?post=20622"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_cat?post=20622"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_tag?post=20622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}