{"id":20592,"date":"2025-11-13T09:00:01","date_gmt":"2025-11-13T09:00:01","guid":{"rendered":"https:\/\/elteuperfum.com\/?post_type=product&#038;p=20592"},"modified":"2025-12-05T13:16:33","modified_gmt":"2025-12-05T13:16:33","slug":"16-equivalencia-dg-light-blue-de-dolcegabbana","status":"publish","type":"product","link":"https:\/\/elteuperfum.com\/ca\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/","title":{"rendered":"#16- Equivalencia D&#038;G Light Blue de Dolce&#038;Gabbana"},"content":{"rendered":"<p>familia olfativa Floral Frutal para Mujeres. Las Notas de Salida son manzana, cedro, campanilla y lim\u00f3n siciliano (lima siciliana).Las Notas de Coraz\u00f3n son rosa blanca, bamb\u00fa y jazm\u00edn. Las Notas de Fondo son \u00e1mbar, almizcle y cedro.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>familia olfativa Floral Frutal para Mujeres. Las Notas de Salida son manzana, cedro, campanilla y lim\u00f3n siciliano (lima siciliana).Las Notas<\/p>\n","protected":false},"featured_media":21984,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[127,104,101],"product_tag":[],"class_list":{"0":"post-20592","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-equivalencia-dolcegabbana","7":"product_cat-para-mujer","8":"product_cat-perfumes","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>#16- Equivalencia D&amp;G Light Blue de Dolce&amp;Gabbana - El teu perfum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#16- Equivalencia D&amp;G Light Blue de Dolce&amp;Gabbana - El teu perfum\" \/>\n<meta property=\"og:description\" content=\"familia olfativa Floral Frutal para Mujeres. Las Notas de Salida son manzana, cedro, campanilla y lim\u00f3n siciliano (lima siciliana).Las Notas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/\" \/>\n<meta property=\"og:site_name\" content=\"El teu perfum\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-05T13:16:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/\",\"url\":\"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/\",\"name\":\"#16- Equivalencia D&G Light Blue de Dolce&Gabbana - El teu perfum\",\"isPartOf\":{\"@id\":\"https:\/\/elteuperfum.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"datePublished\":\"2025-11-13T09:00:01+00:00\",\"dateModified\":\"2025-12-05T13:16:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/#primaryimage\",\"url\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"contentUrl\":\"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg\",\"width\":2000,\"height\":2000,\"caption\":\"Comprar perfumes de equivalencia en El Teu Perfum, en Balaguer.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/elteuperfum.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Botiga\",\"item\":\"https:\/\/elteuperfum.com\/tienda-de-perfumes-online\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"#16- Equivalencia D&#038;G Light Blue de Dolce&#038;Gabbana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elteuperfum.com\/#website\",\"url\":\"https:\/\/elteuperfum.com\/\",\"name\":\"El teu perfum\",\"description\":\"La teva ess\u00e8ncia, al millor preu.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elteuperfum.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#16- Equivalencia D&G Light Blue de Dolce&Gabbana - El teu perfum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/","og_locale":"ca_ES","og_type":"article","og_title":"#16- Equivalencia D&G Light Blue de Dolce&Gabbana - El teu perfum","og_description":"familia olfativa Floral Frutal para Mujeres. Las Notas de Salida son manzana, cedro, campanilla y lim\u00f3n siciliano (lima siciliana).Las Notas","og_url":"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/","og_site_name":"El teu perfum","article_modified_time":"2025-12-05T13:16:33+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/","url":"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/","name":"#16- Equivalencia D&G Light Blue de Dolce&Gabbana - El teu perfum","isPartOf":{"@id":"https:\/\/elteuperfum.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/#primaryimage"},"image":{"@id":"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/#primaryimage"},"thumbnailUrl":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","datePublished":"2025-11-13T09:00:01+00:00","dateModified":"2025-12-05T13:16:33+00:00","breadcrumb":{"@id":"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/#primaryimage","url":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","contentUrl":"https:\/\/elteuperfum.com\/wp-content\/uploads\/2025\/11\/100-ML-FEM.jpg","width":2000,"height":2000,"caption":"Comprar perfumes de equivalencia en El Teu Perfum, en Balaguer."},{"@type":"BreadcrumbList","@id":"https:\/\/elteuperfum.com\/producto\/16-equivalencia-dg-light-blue-de-dolcegabbana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elteuperfum.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Botiga","item":"https:\/\/elteuperfum.com\/tienda-de-perfumes-online\/"},{"@type":"ListItem","position":3,"name":"#16- Equivalencia D&#038;G Light Blue de Dolce&#038;Gabbana"}]},{"@type":"WebSite","@id":"https:\/\/elteuperfum.com\/#website","url":"https:\/\/elteuperfum.com\/","name":"El teu perfum","description":"La teva ess\u00e8ncia, al millor preu.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elteuperfum.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product\/20592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/comments?post=20592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/media\/21984"}],"wp:attachment":[{"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/media?parent=20592"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_brand?post=20592"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_cat?post=20592"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elteuperfum.com\/ca\/wp-json\/wp\/v2\/product_tag?post=20592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}